{"id":3060,"date":"2019-11-04T12:55:53","date_gmt":"2019-11-04T14:55:53","guid":{"rendered":"http:\/\/room33.com.br\/blog\/?p=3060"},"modified":"2020-04-01T09:05:12","modified_gmt":"2020-04-01T12:05:12","slug":"fidelizacao-no-pos-venda","status":"publish","type":"post","link":"https:\/\/room33.com.br\/blog\/2019\/11\/04\/fidelizacao-no-pos-venda\/","title":{"rendered":"[Guest Post] A import\u00e2ncia da fideliza\u00e7\u00e3o no p\u00f3s venda"},"content":{"rendered":"<p class=\"p1\"><span class=\"s1\">Atualmente, o foco das empresas n\u00e3o est\u00e1 apenas em efetuar as vendas de seus servi\u00e7os, mas tamb\u00e9m investir na fideliza\u00e7\u00e3o dos seus clientes ap\u00f3s.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Isso mostra como o mercado mudou, assim como os h\u00e1bitos de consumo da popula\u00e7\u00e3o. Antes de efetuar uma compra, o indiv\u00edduo sempre procura diferentes refer\u00eancias, seja por meio da internet ou pela indica\u00e7\u00e3o de conhecidos.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Sendo assim, para a empresa vale muito a pena fidelizar os seus clientes e mant\u00ea-los pr\u00f3ximos, mesmo ap\u00f3s o processo das vendas j\u00e1 tenha finalizado. Isso garante n\u00e3o apenas que esse cliente volte a comprar com a sua empresa, caso necess\u00e1rio, como tamb\u00e9m auxilia na divulga\u00e7\u00e3o da marca.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Isso tudo parece interessante, n\u00e3o \u00e9 mesmo? Afinal, \u00e9 uma forma de publicidade gratuita, atrav\u00e9s das propagandas que o seu cliente faz a respeito da sua empresa.\u00a0<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Quer entender um pouco mais sobre esse processo?<br \/>\n<\/span><\/p>\n<h2 class=\"p2\"><span class=\"s1\">A import\u00e2ncia da fideliza\u00e7\u00e3o<\/span><\/h2>\n<p class=\"p1\"><span class=\"s1\">O valor de um cliente vai muito al\u00e9m da compra que ele efetua em sua empresa. Isso porque, cada vez mais, as marcas t\u00eam percebido a import\u00e2ncia de cada venda n\u00e3o apenas pelo valor gasto, mas tamb\u00e9m para gerar mais autoridade para a marca.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Isso porque, como foi percebido, cada cliente tem um grande potencial de trazer novas pessoas para a empresa, o que tamb\u00e9m garante mais vendas.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Entretanto, ainda n\u00e3o s\u00e3o todas as empresas que entenderam a import\u00e2ncia da fideliza\u00e7\u00e3o dos seus clientes no p\u00f3s venda. Esse \u00e9 um caminho que est\u00e1 sendo aberto, aos poucos, entre as empresas brasileiras.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Para aquelas que j\u00e1 utilizam isso como estrat\u00e9gia, \u00e9 poss\u00edvel perceber como fazer com que um cliente compre de novo com a sua marca \u00e9 um projeto dif\u00edcil. Ainda assim, esse investimento \u00e9 menor, quando comparado ao CAC (custo de aquisi\u00e7\u00e3o de clientes).<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Por conta disso, esse investimento deve ser repensado dentro das estrat\u00e9gias da empresa, como uma maneira de garantir um maior retorno e, consequentemente, um melhor\u00a0<strong><a href=\"https:\/\/www.marketingparaindustria.com.br\/gestao-vendas\/gestao-empresarial\/fluxo-de-caixa\/\"><span class=\"s2\">fluxo de caixa<\/span><\/a><\/strong>.<\/span><\/p>\n<h2 class=\"p2\"><span class=\"s1\">Estrat\u00e9gias de relacionamento<\/span><\/h2>\n<p class=\"p1\"><span class=\"s1\">A satisfa\u00e7\u00e3o do seu cliente \u00e9 a melhor maneira de medir e descobrir qual \u00e9 a imagem da sua empresa no mercado.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Uma das principais maneiras de mensurar isso \u00e9 atrav\u00e9s da realiza\u00e7\u00e3o de pesquisas com os clientes ap\u00f3s a efetua\u00e7\u00e3o das vendas. Dessa forma, \u00e9 poss\u00edvel entender quais foram os pontos positivos e negativos, do ponto de vista do consumidor.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Ter esse feedback \u00e9 essencial para que a empresa consiga entender em quais pontos \u00e9 necess\u00e1rio melhorar, garantindo uma melhor experi\u00eancia ao consumidor.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Al\u00e9m disso, investir em<a href=\"https:\/\/www.idealmarketing.com.br\/blog\/e-mail-marketing\/\"><span class=\"s2\">\u00a0<strong>e-mail marketing<\/strong><\/span><\/a>\u00a0\u00e9 uma boa estrat\u00e9gia para aqueles que desejam entender a experi\u00eancia do consumidor ap\u00f3s a venda que foi feita.\u00a0<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Da mesma forma, \u00e9 uma \u00f3tima maneira para criar um relacionamento com o seu cliente, principalmente para o\u00a0<strong><a href=\"https:\/\/blog.patrocinioideal.com.br\/markenting-de-relacionamento\/marketing-de-rede\/\"><span class=\"s2\">marketing de rede<\/span><\/a><\/strong>, oferecendo conte\u00fados que sejam interessantes para eles, assim como enviando promo\u00e7\u00f5es relevantes e eventos.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Outra maneira de garantir engajamento do seu p\u00fablico, assim como estabelecer esse bom relacionamento, \u00e9 atrav\u00e9s das redes sociais. Garantir a presen\u00e7a nas m\u00eddias sociais, al\u00e9m de gerar mais autoridade para a marca, tamb\u00e9m \u00e9 um meio mais f\u00e1cil para que o indiv\u00edduo entre em contato, caso seja necess\u00e1rio.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Atualmente, as principais redes sociais s\u00e3o:<\/span><\/p>\n<ul class=\"ul1\">\n<li class=\"li3\"><span class=\"s1\">Facebook;<\/span><\/li>\n<li class=\"li3\"><span class=\"s1\">Twitter;<\/span><\/li>\n<li class=\"li3\"><span class=\"s1\">Instagram;<\/span><\/li>\n<li class=\"li3\"><span class=\"s1\">LinkedIn.<\/span><\/li>\n<\/ul>\n<p class=\"p1\"><span class=\"s1\">Entretanto, \u00e9 importante lembrar que n\u00e3o \u00e9 necess\u00e1rio estar presente em todas essas redes, apenas naquelas em que a sua persona se encontra, garantindo um melhor contato dos dois lados.<\/span><\/p>\n<h2 class=\"p2\"><span class=\"s1\">Encante o seu p\u00fablico!\u00a0<\/span><\/h2>\n<p class=\"p1\"><span class=\"s1\">\u00c9 essencial estar atento \u00e0s necessidades dos seus consumidores, para entender quais as melhores maneiras de estar presente e fazer com que o seu conte\u00fado, assim como a sua empresa, ainda seja relevante mesmo ap\u00f3s a finaliza\u00e7\u00e3o da compra.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">As estrat\u00e9gias do p\u00f3s venda podem ser uma alternativa interessante para as empresas que tem como objetivo fidelizar os seus clientes, garantindo, muitas vezes, uma\u00a0<strong><a href=\"https:\/\/blog.patrocinioideal.com.br\/estilo-de-vida\/renda-extra\/\"><span class=\"s2\">renda extra<\/span><\/a><\/strong>\u00a0por conta da propaga\u00e7\u00e3o que a sua marca vai ter.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Dessa forma, al\u00e9m de fortalecer a autoridade da empresa, tamb\u00e9m \u00e9 poss\u00edvel ter uma publicidade gratuita, tornando o indiv\u00edduo em um embaixador da sua marca, o que pode gerar indica\u00e7\u00f5es e novas vendas.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Isso \u00e9 tudo o que uma empresa pode pedir, n\u00e3o \u00e9 mesmo?<\/span><\/p>\n<p>Conte\u00fado produzido por Let\u00edcia Eleut\u00e9rio | Redatora no\u00a0<strong><a href=\"https:\/\/blog.patrocinioideal.com.br\/\"><span class=\"s2\">Meu Ideal<\/span><\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Atualmente, o foco das empresas n\u00e3o est\u00e1 apenas em efetuar as vendas de seus servi\u00e7os, mas tamb\u00e9m investir na fideliza\u00e7\u00e3o dos seus clientes ap\u00f3s. Isso mostra como o mercado mudou, assim como os h\u00e1bitos de consumo da popula\u00e7\u00e3o. Antes de efetuar uma compra, o indiv\u00edduo sempre procura diferentes refer\u00eancias, seja por meio da internet ou [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3064,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64,65],"tags":[285],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>[Guest Post] A import\u00e2ncia da fideliza\u00e7\u00e3o no p\u00f3s venda - Blog - Room33<\/title>\n<meta name=\"description\" content=\"Investir no marketing p\u00f3s venda garante n\u00e3o apenas que os clientes voltem a comprar com a sua empresa como tamb\u00e9m auxilia na divulga\u00e7\u00e3o da marca\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/room33.com.br\/blog\/2019\/11\/04\/fidelizacao-no-pos-venda\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[Guest Post] A import\u00e2ncia da fideliza\u00e7\u00e3o no p\u00f3s venda - Blog - Room33\" \/>\n<meta property=\"og:description\" content=\"Investir no marketing p\u00f3s venda garante n\u00e3o apenas que os clientes voltem a comprar com a sua empresa como tamb\u00e9m auxilia na divulga\u00e7\u00e3o da marca\" \/>\n<meta property=\"og:url\" content=\"https:\/\/room33.com.br\/blog\/2019\/11\/04\/fidelizacao-no-pos-venda\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog - Room33\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/agenciaroom33\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/roberto.dohan\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-04T14:55:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-01T12:05:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/room33.com.br\/blog\/wp-content\/uploads\/2019\/11\/shutterstock_363968489.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Roberto Dohan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/robertodohan\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Roberto Dohan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/room33.com.br\/blog\/2019\/11\/04\/fidelizacao-no-pos-venda\/\",\"url\":\"https:\/\/room33.com.br\/blog\/2019\/11\/04\/fidelizacao-no-pos-venda\/\",\"name\":\"[Guest Post] A import\u00e2ncia da fideliza\u00e7\u00e3o no p\u00f3s venda - Blog - Room33\",\"isPartOf\":{\"@id\":\"https:\/\/room33.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/room33.com.br\/blog\/2019\/11\/04\/fidelizacao-no-pos-venda\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/room33.com.br\/blog\/2019\/11\/04\/fidelizacao-no-pos-venda\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/room33.com.br\/blog\/wp-content\/uploads\/2019\/11\/shutterstock_363968489.jpg\",\"datePublished\":\"2019-11-04T14:55:53+00:00\",\"dateModified\":\"2020-04-01T12:05:12+00:00\",\"author\":{\"@id\":\"https:\/\/room33.com.br\/blog\/#\/schema\/person\/b7de4397910c79fbdcb658e9c7e98e97\"},\"description\":\"Investir no marketing p\u00f3s venda garante n\u00e3o apenas que os clientes voltem a comprar com a sua empresa como tamb\u00e9m auxilia na divulga\u00e7\u00e3o da marca\",\"breadcrumb\":{\"@id\":\"https:\/\/room33.com.br\/blog\/2019\/11\/04\/fidelizacao-no-pos-venda\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/room33.com.br\/blog\/2019\/11\/04\/fidelizacao-no-pos-venda\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/room33.com.br\/blog\/2019\/11\/04\/fidelizacao-no-pos-venda\/#primaryimage\",\"url\":\"https:\/\/room33.com.br\/blog\/wp-content\/uploads\/2019\/11\/shutterstock_363968489.jpg\",\"contentUrl\":\"https:\/\/room33.com.br\/blog\/wp-content\/uploads\/2019\/11\/shutterstock_363968489.jpg\",\"width\":1000,\"height\":500,\"caption\":\"A import\u00e2ncia da fideliza\u00e7\u00e3o no p\u00f3s venda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/room33.com.br\/blog\/2019\/11\/04\/fidelizacao-no-pos-venda\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/room33.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[Guest Post] A import\u00e2ncia da fideliza\u00e7\u00e3o no p\u00f3s venda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/room33.com.br\/blog\/#website\",\"url\":\"https:\/\/room33.com.br\/blog\/\",\"name\":\"Blog - Room33\",\"description\":\"Blog da ROOM33 - Marketing Digital, M\u00eddias Sociais, Gest\u00e3o de Leads, Marketing Imobili\u00e1rio\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/room33.com.br\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/room33.com.br\/blog\/#\/schema\/person\/b7de4397910c79fbdcb658e9c7e98e97\",\"name\":\"Roberto Dohan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/room33.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/994b12bf35eeac2bfa2f2374810cb444?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/994b12bf35eeac2bfa2f2374810cb444?s=96&r=g\",\"caption\":\"Roberto Dohan\"},\"description\":\"Designer por forma\u00e7\u00e3o, diretor de cria\u00e7\u00e3o por consequ\u00eancia, fot\u00f3grafo por paix\u00e3o. Com 20 anos de experi\u00eancia em design e propaganda, hoje pilota a ROOM33, ag\u00eancia de marketing digital focada, principalmente, em gest\u00e3o e qualifica\u00e7\u00e3o de leads para aumentar as taxas de convers\u00e3o de vendas dos seus clientes. Recebeu diversas vezes os pr\u00eamios Colunistas, Master Imobili\u00e1rio e Top Imobili\u00e1rio.\",\"sameAs\":[\"http:\/\/room33.com.br\/roberto-dohan\/\",\"https:\/\/www.facebook.com\/roberto.dohan\",\"https:\/\/www.instagram.com\/robertodohan\",\"https:\/\/www.linkedin.com\/in\/robertodohan\",\"https:\/\/x.com\/https:\/\/twitter.com\/robertodohan\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[Guest Post] A import\u00e2ncia da fideliza\u00e7\u00e3o no p\u00f3s venda - Blog - Room33","description":"Investir no marketing p\u00f3s venda garante n\u00e3o apenas que os clientes voltem a comprar com a sua empresa como tamb\u00e9m auxilia na divulga\u00e7\u00e3o da marca","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/room33.com.br\/blog\/2019\/11\/04\/fidelizacao-no-pos-venda\/","og_locale":"pt_BR","og_type":"article","og_title":"[Guest Post] A import\u00e2ncia da fideliza\u00e7\u00e3o no p\u00f3s venda - Blog - Room33","og_description":"Investir no marketing p\u00f3s venda garante n\u00e3o apenas que os clientes voltem a comprar com a sua empresa como tamb\u00e9m auxilia na divulga\u00e7\u00e3o da marca","og_url":"https:\/\/room33.com.br\/blog\/2019\/11\/04\/fidelizacao-no-pos-venda\/","og_site_name":"Blog - Room33","article_publisher":"http:\/\/facebook.com\/agenciaroom33","article_author":"https:\/\/www.facebook.com\/roberto.dohan","article_published_time":"2019-11-04T14:55:53+00:00","article_modified_time":"2020-04-01T12:05:12+00:00","og_image":[{"width":1000,"height":500,"url":"https:\/\/room33.com.br\/blog\/wp-content\/uploads\/2019\/11\/shutterstock_363968489.jpg","type":"image\/jpeg"}],"author":"Roberto Dohan","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/robertodohan","twitter_misc":{"Escrito por":"Roberto Dohan","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/room33.com.br\/blog\/2019\/11\/04\/fidelizacao-no-pos-venda\/","url":"https:\/\/room33.com.br\/blog\/2019\/11\/04\/fidelizacao-no-pos-venda\/","name":"[Guest Post] A import\u00e2ncia da fideliza\u00e7\u00e3o no p\u00f3s venda - Blog - Room33","isPartOf":{"@id":"https:\/\/room33.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/room33.com.br\/blog\/2019\/11\/04\/fidelizacao-no-pos-venda\/#primaryimage"},"image":{"@id":"https:\/\/room33.com.br\/blog\/2019\/11\/04\/fidelizacao-no-pos-venda\/#primaryimage"},"thumbnailUrl":"https:\/\/room33.com.br\/blog\/wp-content\/uploads\/2019\/11\/shutterstock_363968489.jpg","datePublished":"2019-11-04T14:55:53+00:00","dateModified":"2020-04-01T12:05:12+00:00","author":{"@id":"https:\/\/room33.com.br\/blog\/#\/schema\/person\/b7de4397910c79fbdcb658e9c7e98e97"},"description":"Investir no marketing p\u00f3s venda garante n\u00e3o apenas que os clientes voltem a comprar com a sua empresa como tamb\u00e9m auxilia na divulga\u00e7\u00e3o da marca","breadcrumb":{"@id":"https:\/\/room33.com.br\/blog\/2019\/11\/04\/fidelizacao-no-pos-venda\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/room33.com.br\/blog\/2019\/11\/04\/fidelizacao-no-pos-venda\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/room33.com.br\/blog\/2019\/11\/04\/fidelizacao-no-pos-venda\/#primaryimage","url":"https:\/\/room33.com.br\/blog\/wp-content\/uploads\/2019\/11\/shutterstock_363968489.jpg","contentUrl":"https:\/\/room33.com.br\/blog\/wp-content\/uploads\/2019\/11\/shutterstock_363968489.jpg","width":1000,"height":500,"caption":"A import\u00e2ncia da fideliza\u00e7\u00e3o no p\u00f3s venda"},{"@type":"BreadcrumbList","@id":"https:\/\/room33.com.br\/blog\/2019\/11\/04\/fidelizacao-no-pos-venda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/room33.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"[Guest Post] A import\u00e2ncia da fideliza\u00e7\u00e3o no p\u00f3s venda"}]},{"@type":"WebSite","@id":"https:\/\/room33.com.br\/blog\/#website","url":"https:\/\/room33.com.br\/blog\/","name":"Blog - Room33","description":"Blog da ROOM33 - Marketing Digital, M\u00eddias Sociais, Gest\u00e3o de Leads, Marketing Imobili\u00e1rio","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/room33.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/room33.com.br\/blog\/#\/schema\/person\/b7de4397910c79fbdcb658e9c7e98e97","name":"Roberto Dohan","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/room33.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/994b12bf35eeac2bfa2f2374810cb444?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/994b12bf35eeac2bfa2f2374810cb444?s=96&r=g","caption":"Roberto Dohan"},"description":"Designer por forma\u00e7\u00e3o, diretor de cria\u00e7\u00e3o por consequ\u00eancia, fot\u00f3grafo por paix\u00e3o. Com 20 anos de experi\u00eancia em design e propaganda, hoje pilota a ROOM33, ag\u00eancia de marketing digital focada, principalmente, em gest\u00e3o e qualifica\u00e7\u00e3o de leads para aumentar as taxas de convers\u00e3o de vendas dos seus clientes. Recebeu diversas vezes os pr\u00eamios Colunistas, Master Imobili\u00e1rio e Top Imobili\u00e1rio.","sameAs":["http:\/\/room33.com.br\/roberto-dohan\/","https:\/\/www.facebook.com\/roberto.dohan","https:\/\/www.instagram.com\/robertodohan","https:\/\/www.linkedin.com\/in\/robertodohan","https:\/\/x.com\/https:\/\/twitter.com\/robertodohan"]}]}},"_links":{"self":[{"href":"https:\/\/room33.com.br\/blog\/wp-json\/wp\/v2\/posts\/3060"}],"collection":[{"href":"https:\/\/room33.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/room33.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/room33.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/room33.com.br\/blog\/wp-json\/wp\/v2\/comments?post=3060"}],"version-history":[{"count":2,"href":"https:\/\/room33.com.br\/blog\/wp-json\/wp\/v2\/posts\/3060\/revisions"}],"predecessor-version":[{"id":3063,"href":"https:\/\/room33.com.br\/blog\/wp-json\/wp\/v2\/posts\/3060\/revisions\/3063"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/room33.com.br\/blog\/wp-json\/wp\/v2\/media\/3064"}],"wp:attachment":[{"href":"https:\/\/room33.com.br\/blog\/wp-json\/wp\/v2\/media?parent=3060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/room33.com.br\/blog\/wp-json\/wp\/v2\/categories?post=3060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/room33.com.br\/blog\/wp-json\/wp\/v2\/tags?post=3060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}